{"id":986,"date":"2019-06-27T12:56:04","date_gmt":"2019-06-27T10:56:04","guid":{"rendered":"https:\/\/mikrobiomik.net\/?p=986"},"modified":"2024-08-29T09:51:51","modified_gmt":"2024-08-29T07:51:51","slug":"mikrobiomik-reaches-final-of-cebek-emprende-awards","status":"publish","type":"post","link":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-reaches-final-of-cebek-emprende-awards\/","title":{"rendered":"Mikrobiomik reaches final of CEBEK Emprende awards"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h2>Mikrobiomik was shortlisted as a finalist for the 2nd CEBEK Emprende awards, sponsored by the Bizkaia Business Confederation.<\/h2>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][image_with_animation image_url=&#8221;974&#8243; alignment=&#8221;&#8221; animation=&#8221;None&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; max_width=&#8221;100%&#8221;][vc_column_text]<em>Left to right: Francisco Javier Azpiazu (CEBEK), Juan Basterra CEO of Mikrobiomik and Marta Mart\u00ednez (CEBEK).<\/em>[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][vc_column_text]&#8221;The CEBEK Emprende awards acknowledge entrepreneurial spirit, business values and innovative schemes, and support recently-incorporated companies that contribute to the economic and social development of Bizkaia&#8221;. &#8211; states<strong>\u00a0Juan Basterra, CEO of Mikrobiomik<\/strong> &#8211; &#8220;We are confident that next year, with a more structured, firmly consolidated company, we will be rated highly enough to win the award.\u201d<\/p>\n<p><a href=\"\/?page_id=20\" target=\"_blank\" rel=\"noopener\">Mikrobiomik<\/a> is a bio-pharmaceutical start-up which was founded with the goal of becoming the first company in the world to register faecal microbiota as a biological medicine in the EU, for use in cases of recurrent Clostridium difficile.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text] Mikrobiomik was shortlisted as a finalist for the 2nd&#8230;<\/p>\n","protected":false},"author":1,"featured_media":975,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,9,70],"tags":[19],"class_list":{"0":"post-986","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-corporate","8":"category-corporativas","9":"category-news-en","10":"tag-cebek"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mikrobiomik reaches final of CEBEK Emprende awards - Mikrobiomik<\/title>\n<meta name=\"description\" content=\"Mikrobiomik was shortlisted as a finalist for the 2nd CEBEK Emprende awards, sponsored by the Bizkaia Business Confederation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mikrobiomik.net\/en\/mikrobiomik-reaches-final-of-cebek-emprende-awards\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mikrobiomik reaches final of CEBEK Emprende awards - Mikrobiomik\" \/>\n<meta property=\"og:description\" content=\"Mikrobiomik was shortlisted as a finalist for the 2nd CEBEK Emprende awards, sponsored by the Bizkaia Business Confederation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mikrobiomik.net\/en\/mikrobiomik-reaches-final-of-cebek-emprende-awards\/\" \/>\n<meta property=\"og:site_name\" content=\"Mikrobiomik\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-27T10:56:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-29T07:51:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mikrobiomik.net\/wp-content\/uploads\/mikrobiomik-cebek.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"elen9miKK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"elen9miKK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-reaches-final-of-cebek-emprende-awards\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-reaches-final-of-cebek-emprende-awards\\\/\"},\"author\":{\"name\":\"elen9miKK\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#\\\/schema\\\/person\\\/5aab4530d1d35b96f96e85aa3d4ca9c9\"},\"headline\":\"Mikrobiomik reaches final of CEBEK Emprende awards\",\"datePublished\":\"2019-06-27T10:56:04+00:00\",\"dateModified\":\"2024-08-29T07:51:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-reaches-final-of-cebek-emprende-awards\\\/\"},\"wordCount\":339,\"publisher\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-reaches-final-of-cebek-emprende-awards\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mikrobiomik.net\\\/wp-content\\\/uploads\\\/mikrobiomik-cebek.jpg\",\"keywords\":[\"Cebek\"],\"articleSection\":[\"Corporate\",\"Corporativas\",\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-reaches-final-of-cebek-emprende-awards\\\/\",\"url\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-reaches-final-of-cebek-emprende-awards\\\/\",\"name\":\"Mikrobiomik reaches final of CEBEK Emprende awards - Mikrobiomik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-reaches-final-of-cebek-emprende-awards\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-reaches-final-of-cebek-emprende-awards\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mikrobiomik.net\\\/wp-content\\\/uploads\\\/mikrobiomik-cebek.jpg\",\"datePublished\":\"2019-06-27T10:56:04+00:00\",\"dateModified\":\"2024-08-29T07:51:51+00:00\",\"description\":\"Mikrobiomik was shortlisted as a finalist for the 2nd CEBEK Emprende awards, sponsored by the Bizkaia Business Confederation.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-reaches-final-of-cebek-emprende-awards\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-reaches-final-of-cebek-emprende-awards\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-reaches-final-of-cebek-emprende-awards\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mikrobiomik.net\\\/wp-content\\\/uploads\\\/mikrobiomik-cebek.jpg\",\"contentUrl\":\"https:\\\/\\\/mikrobiomik.net\\\/wp-content\\\/uploads\\\/mikrobiomik-cebek.jpg\",\"width\":800,\"height\":600,\"caption\":\"De izquierda a derecha: Francisco Javier Azpiazu, Secretario General de CEBEK, Juan Basterra CEO de Mikrobiomik y Marta Mart\u00ednez, Responsable de Emprendimiento y Gesti\u00f3n de Personas en CEBEK\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-reaches-final-of-cebek-emprende-awards\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mikrobiomik.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mikrobiomik reaches final of CEBEK Emprende awards\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#website\",\"url\":\"https:\\\/\\\/mikrobiomik.net\\\/\",\"name\":\"Mikrobiomik\",\"description\":\"Terapias biol\u00f3gicas\",\"publisher\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mikrobiomik.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#organization\",\"name\":\"Mikrobiomik\",\"url\":\"https:\\\/\\\/mikrobiomik.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mikrobiomik.net\\\/wp-content\\\/uploads\\\/mikrobiomik-600.png\",\"contentUrl\":\"https:\\\/\\\/mikrobiomik.net\\\/wp-content\\\/uploads\\\/mikrobiomik-600.png\",\"width\":600,\"height\":171,\"caption\":\"Mikrobiomik\"},\"image\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mikrobiomik\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#\\\/schema\\\/person\\\/5aab4530d1d35b96f96e85aa3d4ca9c9\",\"name\":\"elen9miKK\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mikrobiomik reaches final of CEBEK Emprende awards - Mikrobiomik","description":"Mikrobiomik was shortlisted as a finalist for the 2nd CEBEK Emprende awards, sponsored by the Bizkaia Business Confederation.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-reaches-final-of-cebek-emprende-awards\/","og_locale":"en_US","og_type":"article","og_title":"Mikrobiomik reaches final of CEBEK Emprende awards - Mikrobiomik","og_description":"Mikrobiomik was shortlisted as a finalist for the 2nd CEBEK Emprende awards, sponsored by the Bizkaia Business Confederation.","og_url":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-reaches-final-of-cebek-emprende-awards\/","og_site_name":"Mikrobiomik","article_published_time":"2019-06-27T10:56:04+00:00","article_modified_time":"2024-08-29T07:51:51+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/mikrobiomik-cebek.jpg","type":"image\/jpeg"}],"author":"elen9miKK","twitter_card":"summary_large_image","twitter_misc":{"Written by":"elen9miKK","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-reaches-final-of-cebek-emprende-awards\/#article","isPartOf":{"@id":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-reaches-final-of-cebek-emprende-awards\/"},"author":{"name":"elen9miKK","@id":"https:\/\/mikrobiomik.net\/#\/schema\/person\/5aab4530d1d35b96f96e85aa3d4ca9c9"},"headline":"Mikrobiomik reaches final of CEBEK Emprende awards","datePublished":"2019-06-27T10:56:04+00:00","dateModified":"2024-08-29T07:51:51+00:00","mainEntityOfPage":{"@id":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-reaches-final-of-cebek-emprende-awards\/"},"wordCount":339,"publisher":{"@id":"https:\/\/mikrobiomik.net\/#organization"},"image":{"@id":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-reaches-final-of-cebek-emprende-awards\/#primaryimage"},"thumbnailUrl":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/mikrobiomik-cebek.jpg","keywords":["Cebek"],"articleSection":["Corporate","Corporativas","News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-reaches-final-of-cebek-emprende-awards\/","url":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-reaches-final-of-cebek-emprende-awards\/","name":"Mikrobiomik reaches final of CEBEK Emprende awards - Mikrobiomik","isPartOf":{"@id":"https:\/\/mikrobiomik.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-reaches-final-of-cebek-emprende-awards\/#primaryimage"},"image":{"@id":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-reaches-final-of-cebek-emprende-awards\/#primaryimage"},"thumbnailUrl":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/mikrobiomik-cebek.jpg","datePublished":"2019-06-27T10:56:04+00:00","dateModified":"2024-08-29T07:51:51+00:00","description":"Mikrobiomik was shortlisted as a finalist for the 2nd CEBEK Emprende awards, sponsored by the Bizkaia Business Confederation.","breadcrumb":{"@id":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-reaches-final-of-cebek-emprende-awards\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mikrobiomik.net\/en\/mikrobiomik-reaches-final-of-cebek-emprende-awards\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-reaches-final-of-cebek-emprende-awards\/#primaryimage","url":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/mikrobiomik-cebek.jpg","contentUrl":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/mikrobiomik-cebek.jpg","width":800,"height":600,"caption":"De izquierda a derecha: Francisco Javier Azpiazu, Secretario General de CEBEK, Juan Basterra CEO de Mikrobiomik y Marta Mart\u00ednez, Responsable de Emprendimiento y Gesti\u00f3n de Personas en CEBEK"},{"@type":"BreadcrumbList","@id":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-reaches-final-of-cebek-emprende-awards\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mikrobiomik.net\/"},{"@type":"ListItem","position":2,"name":"Mikrobiomik reaches final of CEBEK Emprende awards"}]},{"@type":"WebSite","@id":"https:\/\/mikrobiomik.net\/#website","url":"https:\/\/mikrobiomik.net\/","name":"Mikrobiomik","description":"Terapias biol\u00f3gicas","publisher":{"@id":"https:\/\/mikrobiomik.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mikrobiomik.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mikrobiomik.net\/#organization","name":"Mikrobiomik","url":"https:\/\/mikrobiomik.net\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mikrobiomik.net\/#\/schema\/logo\/image\/","url":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/mikrobiomik-600.png","contentUrl":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/mikrobiomik-600.png","width":600,"height":171,"caption":"Mikrobiomik"},"image":{"@id":"https:\/\/mikrobiomik.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/mikrobiomik"]},{"@type":"Person","@id":"https:\/\/mikrobiomik.net\/#\/schema\/person\/5aab4530d1d35b96f96e85aa3d4ca9c9","name":"elen9miKK"}]}},"_links":{"self":[{"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/posts\/986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/comments?post=986"}],"version-history":[{"count":3,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/posts\/986\/revisions"}],"predecessor-version":[{"id":989,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/posts\/986\/revisions\/989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/media\/975"}],"wp:attachment":[{"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/media?parent=986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/categories?post=986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/tags?post=986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}