{"id":2816,"date":"2024-03-08T18:05:51","date_gmt":"2024-03-08T17:05:51","guid":{"rendered":"https:\/\/mikrobiomik.net\/?p=2816"},"modified":"2024-08-29T09:48:52","modified_gmt":"2024-08-29T07:48:52","slug":"celebrating-female-talent-at-mikrobiomik","status":"publish","type":"post","link":"https:\/\/mikrobiomik.net\/en\/celebrating-female-talent-at-mikrobiomik\/","title":{"rendered":"Celebrating Female Talent at Mikrobiomik"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text text_direction=&#8221;default&#8221;]\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2819\" src=\"https:\/\/mikrobiomik.net\/wp-content\/uploads\/talento-femenino-mikrobiomik.jpg\" alt=\"Talento femenino en Mikrobiomik\" width=\"1921\" height=\"1318\" srcset=\"https:\/\/mikrobiomik.net\/wp-content\/uploads\/talento-femenino-mikrobiomik.jpg 1921w, https:\/\/mikrobiomik.net\/wp-content\/uploads\/talento-femenino-mikrobiomik-300x206.jpg 300w, https:\/\/mikrobiomik.net\/wp-content\/uploads\/talento-femenino-mikrobiomik-1024x703.jpg 1024w, https:\/\/mikrobiomik.net\/wp-content\/uploads\/talento-femenino-mikrobiomik-768x527.jpg 768w, https:\/\/mikrobiomik.net\/wp-content\/uploads\/talento-femenino-mikrobiomik-1536x1054.jpg 1536w\" sizes=\"auto, (max-width: 1921px) 100vw, 1921px\" \/><\/p>\n<p>On Friday, March 8th, at Mikrobiomik, we took a moment to honor and celebrate<strong> the women who represent 90% of our team of professionals.<\/strong> As a diverse and inclusive group, with women from diverse disciplines such as <strong>biology, pharmacy, biochemistry, and economics <\/strong>who not only enrich our projects, but also are leading important departments and perform senior management roles.<\/p>\n<p>To commemorate their invaluable contribution, we held a <strong>reflection activity.<\/strong> We recognized the talent and dedication that each of them brings to our company, and shared a snack, marking the end of an intense week of work. At Mikrobiomik, we promote inclusion and value the crucial role that women play in our team.<\/p>\n<p>Their experience and expertise inspire our daily work and push us towards a more equal and promising future. In memory of this special date, on International Women&#8217;s Day, we celebrate the excellence and unlimited potential that our professional women bring to our team and to the microbiota field.<\/p>\n<p>&nbsp;<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2819,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,70],"tags":[],"class_list":{"0":"post-2816","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-corporate","8":"category-news-en"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Celebrating Female Talent at Mikrobiomik - Mikrobiomik<\/title>\n<meta name=\"description\" content=\"At Mikrobiomik we celebrate female talent on March 8. Women make up 90% of our team of professionals.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mikrobiomik.net\/en\/celebrating-female-talent-at-mikrobiomik\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebrating Female Talent at Mikrobiomik - Mikrobiomik\" \/>\n<meta property=\"og:description\" content=\"At Mikrobiomik we celebrate female talent on March 8. Women make up 90% of our team of professionals.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mikrobiomik.net\/en\/celebrating-female-talent-at-mikrobiomik\/\" \/>\n<meta property=\"og:site_name\" content=\"Mikrobiomik\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-08T17:05:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-29T07:48:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mikrobiomik.net\/wp-content\/uploads\/talento-femenino-mikrobiomik.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1921\" \/>\n\t<meta property=\"og:image:height\" content=\"1318\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"elen9miKK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"elen9miKK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/celebrating-female-talent-at-mikrobiomik\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/celebrating-female-talent-at-mikrobiomik\\\/\"},\"author\":{\"name\":\"elen9miKK\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#\\\/schema\\\/person\\\/5aab4530d1d35b96f96e85aa3d4ca9c9\"},\"headline\":\"Celebrating Female Talent at Mikrobiomik\",\"datePublished\":\"2024-03-08T17:05:51+00:00\",\"dateModified\":\"2024-08-29T07:48:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/celebrating-female-talent-at-mikrobiomik\\\/\"},\"wordCount\":331,\"publisher\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/celebrating-female-talent-at-mikrobiomik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mikrobiomik.net\\\/wp-content\\\/uploads\\\/talento-femenino-mikrobiomik.jpg\",\"articleSection\":[\"Corporate\",\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/celebrating-female-talent-at-mikrobiomik\\\/\",\"url\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/celebrating-female-talent-at-mikrobiomik\\\/\",\"name\":\"Celebrating Female Talent at Mikrobiomik - Mikrobiomik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/celebrating-female-talent-at-mikrobiomik\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/celebrating-female-talent-at-mikrobiomik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mikrobiomik.net\\\/wp-content\\\/uploads\\\/talento-femenino-mikrobiomik.jpg\",\"datePublished\":\"2024-03-08T17:05:51+00:00\",\"dateModified\":\"2024-08-29T07:48:52+00:00\",\"description\":\"At Mikrobiomik we celebrate female talent on March 8. Women make up 90% of our team of professionals.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/celebrating-female-talent-at-mikrobiomik\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/celebrating-female-talent-at-mikrobiomik\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/celebrating-female-talent-at-mikrobiomik\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mikrobiomik.net\\\/wp-content\\\/uploads\\\/talento-femenino-mikrobiomik.jpg\",\"contentUrl\":\"https:\\\/\\\/mikrobiomik.net\\\/wp-content\\\/uploads\\\/talento-femenino-mikrobiomik.jpg\",\"width\":1921,\"height\":1318,\"caption\":\"Talento femenino en Mikrobiomik\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/celebrating-female-talent-at-mikrobiomik\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mikrobiomik.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celebrating Female Talent at Mikrobiomik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#website\",\"url\":\"https:\\\/\\\/mikrobiomik.net\\\/\",\"name\":\"Mikrobiomik\",\"description\":\"Terapias biol\u00f3gicas\",\"publisher\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mikrobiomik.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#organization\",\"name\":\"Mikrobiomik\",\"url\":\"https:\\\/\\\/mikrobiomik.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mikrobiomik.net\\\/wp-content\\\/uploads\\\/mikrobiomik-600.png\",\"contentUrl\":\"https:\\\/\\\/mikrobiomik.net\\\/wp-content\\\/uploads\\\/mikrobiomik-600.png\",\"width\":600,\"height\":171,\"caption\":\"Mikrobiomik\"},\"image\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mikrobiomik\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#\\\/schema\\\/person\\\/5aab4530d1d35b96f96e85aa3d4ca9c9\",\"name\":\"elen9miKK\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Celebrating Female Talent at Mikrobiomik - Mikrobiomik","description":"At Mikrobiomik we celebrate female talent on March 8. Women make up 90% of our team of professionals.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mikrobiomik.net\/en\/celebrating-female-talent-at-mikrobiomik\/","og_locale":"en_US","og_type":"article","og_title":"Celebrating Female Talent at Mikrobiomik - Mikrobiomik","og_description":"At Mikrobiomik we celebrate female talent on March 8. Women make up 90% of our team of professionals.","og_url":"https:\/\/mikrobiomik.net\/en\/celebrating-female-talent-at-mikrobiomik\/","og_site_name":"Mikrobiomik","article_published_time":"2024-03-08T17:05:51+00:00","article_modified_time":"2024-08-29T07:48:52+00:00","og_image":[{"width":1921,"height":1318,"url":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/talento-femenino-mikrobiomik.jpg","type":"image\/jpeg"}],"author":"elen9miKK","twitter_card":"summary_large_image","twitter_misc":{"Written by":"elen9miKK","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mikrobiomik.net\/en\/celebrating-female-talent-at-mikrobiomik\/#article","isPartOf":{"@id":"https:\/\/mikrobiomik.net\/en\/celebrating-female-talent-at-mikrobiomik\/"},"author":{"name":"elen9miKK","@id":"https:\/\/mikrobiomik.net\/#\/schema\/person\/5aab4530d1d35b96f96e85aa3d4ca9c9"},"headline":"Celebrating Female Talent at Mikrobiomik","datePublished":"2024-03-08T17:05:51+00:00","dateModified":"2024-08-29T07:48:52+00:00","mainEntityOfPage":{"@id":"https:\/\/mikrobiomik.net\/en\/celebrating-female-talent-at-mikrobiomik\/"},"wordCount":331,"publisher":{"@id":"https:\/\/mikrobiomik.net\/#organization"},"image":{"@id":"https:\/\/mikrobiomik.net\/en\/celebrating-female-talent-at-mikrobiomik\/#primaryimage"},"thumbnailUrl":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/talento-femenino-mikrobiomik.jpg","articleSection":["Corporate","News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/mikrobiomik.net\/en\/celebrating-female-talent-at-mikrobiomik\/","url":"https:\/\/mikrobiomik.net\/en\/celebrating-female-talent-at-mikrobiomik\/","name":"Celebrating Female Talent at Mikrobiomik - Mikrobiomik","isPartOf":{"@id":"https:\/\/mikrobiomik.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mikrobiomik.net\/en\/celebrating-female-talent-at-mikrobiomik\/#primaryimage"},"image":{"@id":"https:\/\/mikrobiomik.net\/en\/celebrating-female-talent-at-mikrobiomik\/#primaryimage"},"thumbnailUrl":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/talento-femenino-mikrobiomik.jpg","datePublished":"2024-03-08T17:05:51+00:00","dateModified":"2024-08-29T07:48:52+00:00","description":"At Mikrobiomik we celebrate female talent on March 8. Women make up 90% of our team of professionals.","breadcrumb":{"@id":"https:\/\/mikrobiomik.net\/en\/celebrating-female-talent-at-mikrobiomik\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mikrobiomik.net\/en\/celebrating-female-talent-at-mikrobiomik\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mikrobiomik.net\/en\/celebrating-female-talent-at-mikrobiomik\/#primaryimage","url":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/talento-femenino-mikrobiomik.jpg","contentUrl":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/talento-femenino-mikrobiomik.jpg","width":1921,"height":1318,"caption":"Talento femenino en Mikrobiomik"},{"@type":"BreadcrumbList","@id":"https:\/\/mikrobiomik.net\/en\/celebrating-female-talent-at-mikrobiomik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mikrobiomik.net\/"},{"@type":"ListItem","position":2,"name":"Celebrating Female Talent at Mikrobiomik"}]},{"@type":"WebSite","@id":"https:\/\/mikrobiomik.net\/#website","url":"https:\/\/mikrobiomik.net\/","name":"Mikrobiomik","description":"Terapias biol\u00f3gicas","publisher":{"@id":"https:\/\/mikrobiomik.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mikrobiomik.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mikrobiomik.net\/#organization","name":"Mikrobiomik","url":"https:\/\/mikrobiomik.net\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mikrobiomik.net\/#\/schema\/logo\/image\/","url":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/mikrobiomik-600.png","contentUrl":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/mikrobiomik-600.png","width":600,"height":171,"caption":"Mikrobiomik"},"image":{"@id":"https:\/\/mikrobiomik.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/mikrobiomik"]},{"@type":"Person","@id":"https:\/\/mikrobiomik.net\/#\/schema\/person\/5aab4530d1d35b96f96e85aa3d4ca9c9","name":"elen9miKK"}]}},"_links":{"self":[{"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/posts\/2816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/comments?post=2816"}],"version-history":[{"count":7,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/posts\/2816\/revisions"}],"predecessor-version":[{"id":2828,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/posts\/2816\/revisions\/2828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/media\/2819"}],"wp:attachment":[{"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/media?parent=2816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/categories?post=2816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/tags?post=2816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}