{"id":1358,"date":"2022-01-12T10:50:22","date_gmt":"2022-01-12T09:50:22","guid":{"rendered":"https:\/\/mikrobiomik.net\/?p=1358"},"modified":"2024-08-29T09:51:26","modified_gmt":"2024-08-29T07:51:26","slug":"mikrobiomik-on-television","status":"publish","type":"post","link":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-on-television\/","title":{"rendered":"Mikrobiomik on television"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h2>Mikrobiomik on TV.<\/h2>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]Last weekend we had the pleasure of appearing on the ETB programme Teknopolis. On this occasion and in a simple way, we explained to the public what we do at Mikrobiomik with such a peculiar raw material, human faeces, with the aim of developing the first biological medicine based on faecal microbiota.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1361&#8243; animation=&#8221;None&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]Without a doubt, it was a great opportunity to explain our work as one of the companies that is committed to treatment with products based on microbiota intestinal and with an important therapeutic base that can lead to the treatment of chronic diseases or diseases for which there is currently no cure.<\/p>\n<p>You can see the full report here (in Spanish):[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;50&#8243;][vc_raw_html]JTNDZGl2JTIwc3R5bGUlM0QlMjIlMjBwb3NpdGlvbiUzQSUyMHJlbGF0aXZlJTNCcGFkZGluZy1ib3R0b20lM0ElMjA1Ni4yNSUyNSUzQnBhZGRpbmctdG9wJTNBJTIwMzVweCUzQmhlaWdodCUzQSUyMDAlM0JvdmVyZmxvdyUzQSUyMGhpZGRlbiUzQiUyMiUzRSUwQSUwOSUwOSUwOSUwOSUwOSUzQ2lmcmFtZSUyMHNjcm9sbGluZyUzRCUyMm5vJTIyJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZ3d3cuZWl0Yi5ldXMlMkZlcyUyRmdldCUyRm11bHRpbWVkaWElMkZzY3JlZW4lMkZpZCUyRjg1NjgxNTIlMkZ0aXBvJTJGdmlkZW9zJTJGdGVsZXZpc2lvbiUyRnRla25vcG9saXMlMkYlMjIlMjBmcmFtZWJvcmRlciUzRCUyMjAlMjIlMjBtYXJnaW53aWR0aCUzRCUyMjAlMjIlMjBtYXJnaW5oZWlnaHQlM0QlMjIwJTIyJTIwc2Nyb2xsaW5nJTNEJTIybm8lMjIlMjBzdHlsZSUzRCUyMnBvc2l0aW9uJTNBJTIwYWJzb2x1dGUlM0J0b3AlM0EwJTNCbGVmdCUzQSUyMDAlM0J3aWR0aCUzQSUyMDEwMCUyNSUzQmhlaWdodCUzQSUyMDEwMCUyNSUzQiUyMiUyMCUzRSUzQyUyRmlmcmFtZSUzRSUzQyUyRmRpdiUzRQ==[\/vc_raw_html][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1361,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,9,70],"tags":[],"class_list":{"0":"post-1358","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-corporate","8":"category-corporativas","9":"category-news-en"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mikrobiomik on television - Mikrobiomik<\/title>\n<meta name=\"description\" content=\"Mikrobiomik explained what we do with human faeces with the aim of developing the first biological medicine based on faecal microbiota.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mikrobiomik.net\/en\/mikrobiomik-on-television\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mikrobiomik on television - Mikrobiomik\" \/>\n<meta property=\"og:description\" content=\"Mikrobiomik explained what we do with human faeces with the aim of developing the first biological medicine based on faecal microbiota.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mikrobiomik.net\/en\/mikrobiomik-on-television\/\" \/>\n<meta property=\"og:site_name\" content=\"Mikrobiomik\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-12T09:50:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-29T07:51:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mikrobiomik.net\/wp-content\/uploads\/mikrobiomik-en-television.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"elen9miKK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"elen9miKK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-on-television\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-on-television\\\/\"},\"author\":{\"name\":\"elen9miKK\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#\\\/schema\\\/person\\\/5aab4530d1d35b96f96e85aa3d4ca9c9\"},\"headline\":\"Mikrobiomik on television\",\"datePublished\":\"2022-01-12T09:50:22+00:00\",\"dateModified\":\"2024-08-29T07:51:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-on-television\\\/\"},\"wordCount\":783,\"publisher\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-on-television\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mikrobiomik.net\\\/wp-content\\\/uploads\\\/mikrobiomik-en-television.jpg\",\"articleSection\":[\"Corporate\",\"Corporativas\",\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-on-television\\\/\",\"url\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-on-television\\\/\",\"name\":\"Mikrobiomik on television - Mikrobiomik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-on-television\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-on-television\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mikrobiomik.net\\\/wp-content\\\/uploads\\\/mikrobiomik-en-television.jpg\",\"datePublished\":\"2022-01-12T09:50:22+00:00\",\"dateModified\":\"2024-08-29T07:51:26+00:00\",\"description\":\"Mikrobiomik explained what we do with human faeces with the aim of developing the first biological medicine based on faecal microbiota.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-on-television\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-on-television\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-on-television\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mikrobiomik.net\\\/wp-content\\\/uploads\\\/mikrobiomik-en-television.jpg\",\"contentUrl\":\"https:\\\/\\\/mikrobiomik.net\\\/wp-content\\\/uploads\\\/mikrobiomik-en-television.jpg\",\"width\":1024,\"height\":540,\"caption\":\"Mikrobiomik en televisi\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/en\\\/mikrobiomik-on-television\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mikrobiomik.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mikrobiomik on television\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#website\",\"url\":\"https:\\\/\\\/mikrobiomik.net\\\/\",\"name\":\"Mikrobiomik\",\"description\":\"Terapias biol\u00f3gicas\",\"publisher\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mikrobiomik.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#organization\",\"name\":\"Mikrobiomik\",\"url\":\"https:\\\/\\\/mikrobiomik.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mikrobiomik.net\\\/wp-content\\\/uploads\\\/mikrobiomik-600.png\",\"contentUrl\":\"https:\\\/\\\/mikrobiomik.net\\\/wp-content\\\/uploads\\\/mikrobiomik-600.png\",\"width\":600,\"height\":171,\"caption\":\"Mikrobiomik\"},\"image\":{\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mikrobiomik\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mikrobiomik.net\\\/#\\\/schema\\\/person\\\/5aab4530d1d35b96f96e85aa3d4ca9c9\",\"name\":\"elen9miKK\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mikrobiomik on television - Mikrobiomik","description":"Mikrobiomik explained what we do with human faeces with the aim of developing the first biological medicine based on faecal microbiota.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-on-television\/","og_locale":"en_US","og_type":"article","og_title":"Mikrobiomik on television - Mikrobiomik","og_description":"Mikrobiomik explained what we do with human faeces with the aim of developing the first biological medicine based on faecal microbiota.","og_url":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-on-television\/","og_site_name":"Mikrobiomik","article_published_time":"2022-01-12T09:50:22+00:00","article_modified_time":"2024-08-29T07:51:26+00:00","og_image":[{"width":1024,"height":540,"url":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/mikrobiomik-en-television.jpg","type":"image\/jpeg"}],"author":"elen9miKK","twitter_card":"summary_large_image","twitter_misc":{"Written by":"elen9miKK","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-on-television\/#article","isPartOf":{"@id":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-on-television\/"},"author":{"name":"elen9miKK","@id":"https:\/\/mikrobiomik.net\/#\/schema\/person\/5aab4530d1d35b96f96e85aa3d4ca9c9"},"headline":"Mikrobiomik on television","datePublished":"2022-01-12T09:50:22+00:00","dateModified":"2024-08-29T07:51:26+00:00","mainEntityOfPage":{"@id":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-on-television\/"},"wordCount":783,"publisher":{"@id":"https:\/\/mikrobiomik.net\/#organization"},"image":{"@id":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-on-television\/#primaryimage"},"thumbnailUrl":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/mikrobiomik-en-television.jpg","articleSection":["Corporate","Corporativas","News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-on-television\/","url":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-on-television\/","name":"Mikrobiomik on television - Mikrobiomik","isPartOf":{"@id":"https:\/\/mikrobiomik.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-on-television\/#primaryimage"},"image":{"@id":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-on-television\/#primaryimage"},"thumbnailUrl":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/mikrobiomik-en-television.jpg","datePublished":"2022-01-12T09:50:22+00:00","dateModified":"2024-08-29T07:51:26+00:00","description":"Mikrobiomik explained what we do with human faeces with the aim of developing the first biological medicine based on faecal microbiota.","breadcrumb":{"@id":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-on-television\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mikrobiomik.net\/en\/mikrobiomik-on-television\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-on-television\/#primaryimage","url":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/mikrobiomik-en-television.jpg","contentUrl":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/mikrobiomik-en-television.jpg","width":1024,"height":540,"caption":"Mikrobiomik en televisi\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/mikrobiomik.net\/en\/mikrobiomik-on-television\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mikrobiomik.net\/"},{"@type":"ListItem","position":2,"name":"Mikrobiomik on television"}]},{"@type":"WebSite","@id":"https:\/\/mikrobiomik.net\/#website","url":"https:\/\/mikrobiomik.net\/","name":"Mikrobiomik","description":"Terapias biol\u00f3gicas","publisher":{"@id":"https:\/\/mikrobiomik.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mikrobiomik.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mikrobiomik.net\/#organization","name":"Mikrobiomik","url":"https:\/\/mikrobiomik.net\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mikrobiomik.net\/#\/schema\/logo\/image\/","url":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/mikrobiomik-600.png","contentUrl":"https:\/\/mikrobiomik.net\/wp-content\/uploads\/mikrobiomik-600.png","width":600,"height":171,"caption":"Mikrobiomik"},"image":{"@id":"https:\/\/mikrobiomik.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/mikrobiomik"]},{"@type":"Person","@id":"https:\/\/mikrobiomik.net\/#\/schema\/person\/5aab4530d1d35b96f96e85aa3d4ca9c9","name":"elen9miKK"}]}},"_links":{"self":[{"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/posts\/1358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/comments?post=1358"}],"version-history":[{"count":2,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/posts\/1358\/revisions"}],"predecessor-version":[{"id":1367,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/posts\/1358\/revisions\/1367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/media\/1361"}],"wp:attachment":[{"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/media?parent=1358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/categories?post=1358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mikrobiomik.net\/en\/wp-json\/wp\/v2\/tags?post=1358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}